{"id":794,"date":"2025-07-22T10:15:33","date_gmt":"2025-07-22T10:15:33","guid":{"rendered":"https:\/\/franciscansinternational.org\/de\/?post_type=reflection&#038;p=794"},"modified":"2025-07-22T10:15:35","modified_gmt":"2025-07-22T10:15:35","slug":"gelobt-seist-du-mein-herr-durch-bruder-feuer","status":"publish","type":"reflection","link":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/","title":{"rendered":"Gelobt seist du, mein Herr, durch Bruder Feuer&#8230;"},"content":{"rendered":"\n<p><em>Dieser Artikel ist Teil einer <a href=\"https:\/\/franciscansinternational.org\/de\/wir-feiern-den-sonnengesang\/\" target=\"_blank\" rel=\"noreferrer noopener\">Reihe von Betrachtungen<\/a>, die von unserem <a href=\"https:\/\/franciscansinternational.org\/de\/ueber-uns\/#internationalervorstand\" target=\"_blank\" rel=\"noreferrer noopener\">internationalen Vorstand<\/a> anl\u00e4sslich des 800-j\u00e4hrigen Jubil\u00e4ums des Sonnengesangs verfasst wurden.<\/em><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-color has-text-color has-link-color wp-elements-1c436cee45f1c494dfd5a54875f61579\">\u2022 \u2022 \u2022<\/p>\n\n\n\n<p>Feuer ist gef\u00e4hrlich und verspielt zugleich.<\/p>\n\n\n\n<p>Es ist n\u00fctzlich und zerst\u00f6rerisch.<\/p>\n\n\n\n<p>Notwendig und doch gef\u00fcrchtet.<\/p>\n\n\n\n<p>Es wird durch sorgf\u00e4ltige Vorsichtsma\u00dfnahmen gez\u00e4hmt, damit es nicht au\u00dfer Kontrolle ger\u00e4t.<\/p>\n\n\n\n<p>Seine Hitze verwandelt die Rohstoffe von Wurzeln, Fischen oder Tierfleisch in Nahrung, die wir essen k\u00f6nnen und die uns erh\u00e4lt.<\/p>\n\n\n\n<p>Seine Hitze w\u00e4rmt uns, wenn es kalt ist, und sch\u00fctzt uns nachts vor Raubtieren.<\/p>\n\n\n\n<p>Doch seine Gefahr lauert und kann jederzeit zuschlagen, wenn wir nicht st\u00e4ndig wachsam sind.<\/p>\n\n\n\n<p>Seine zerst\u00f6rerische Kraft kann ganze W\u00e4lder vernichten, aber es gibt B\u00e4ume, deren Samen die Hitze des Feuers brauchen, um keimen zu k\u00f6nnen.<\/p>\n\n\n\n<p>Viele Sch\u00f6pfungsgeschichten aus vielen Kulturen rund um die Welt erz\u00e4hlen davon, wie das Feuer durch List oder Diebstahl von den alten G\u00f6ttern oder durch heldenhafte Reisen an ferne und gef\u00e4hrliche Orte erlangt wurde.<\/p>\n\n\n\n<p>Solche Geschichten lehren uns, die Natur und das G\u00f6ttliche zu respektieren.<\/p>\n\n\n\n<p>Sie erz\u00e4hlen vom Wert der Gemeinschaft und der Zusammenarbeit, um gemeinsame Ziele zu erreichen.<\/p>\n\n\n\n<p>Und sie erz\u00e4hlen von der Bedeutung von Mut und Intelligenz angesichts von Widrigkeiten.<\/p>\n\n\n\n<p>Franz von Assisi spricht in seinem Sonnengesang vom Feuer als Bruder.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Gelobt seist du, mein Herr,<\/em><br><em>durch Bruder Feuer,<\/em><br><em>durch den du die Nacht erleuchtest,<\/em><br><em>und er ist sch\u00f6n und verspielt<\/em><br><em>und robust und stark.<\/em><\/p>\n\n\n\n<p>In Franziskus&#8216; Vision war das Feuer nicht l\u00e4nger etwas Launenhaftes oder Sinnloses. Er lobt Gott durch es und f\u00fcr es. Es hat einen Platz in der sch\u00f6nen Ordnung der Sch\u00f6pfung Gottes. Er hatte sogar keine Angst vor dem gl\u00fchenden Eisen, das bei der Operation an seinen Augen verwendet wurde, denn er vertraute darauf, dass das Feuer, so wie er es respektiert und behutsam behandelt hatte, auch ihm gegen\u00fcber behutsam sein w\u00fcrde.<\/p>\n\n\n\n<p>Wir beten f\u00fcr unseren Umgang mit diesem kostbaren Geschenk Gottes und f\u00fcr unsere Beziehung zu ihm.<\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Herr der Sch\u00f6pfung.<\/em><br><em>Erh\u00f6re unser Gebet.<\/em><br><em>Wir beten f\u00fcr einen richtigen Umgang mit dem Feuer und f\u00fcr die W\u00fcrdigung all dessen, was es uns schenkt. W\u00e4rme zum Heizen und Kochen. F\u00fcr unsere Sicherheit.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Herr der Sch\u00f6pfung.<\/em><br><em>Erh\u00f6re unser Gebet.<\/em><br><em>Wir beten f\u00fcr diejenigen, die dieses Geschenk missbrauchen. Die das Feuer benutzen, um zu zerst\u00f6ren und anderen zu schaden.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Herr der Sch\u00f6pfung.<\/em><br><em>Erh\u00f6re unser Gebet.<\/em><br><em>Wir beten f\u00fcr unsere gesamte Umwelt. Feuer hat seinen Platz, kann aber zur globalen Erw\u00e4rmung beitragen.<\/em> <em>Geben Sie uns Weisheit und die F\u00e4higkeit, das Geschenk des Feuers zum Wohle aller zu nutzen.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Herr der Sch\u00f6pfung.<\/em><br><em>Erh\u00f6re unser Gebet.<\/em><br><em>Gesegnet seist du, Gott des Universums, denn Feuer ist ein Symbol f\u00fcr deinen lebensspendenden und herausfordernden Geist \u2013 der immer im Licht tanzt, unsere Todesschmerzen zerst\u00f6rt und unserem Leben in Jesus Christus, unserem Erl\u00f6ser, Erneuerung bringt.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-left\"><em>Amen.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>&#8211; Br. Christopher John SSF<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-small-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Dies ist eine automatische \u00dcbersetzung. Wir entschuldigen uns f\u00fcr eventuelle Fehler, die dadurch entstanden sind. Im Falle von Abweichungen ist die englische Fassung ma\u00dfgebend.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Dieser Artikel ist Teil einer Reihe von Betrachtungen, die von unserem internationalen Vorstand anl\u00e4sslich des 800-j\u00e4hrigen Jubil\u00e4ums des Sonnengesangs verfasst &#8230; <\/p>\n","protected":false},"featured_media":795,"template":"","class_list":["post-794","reflection","type-reflection","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gelobt seist du, mein Herr, durch Bruder Feuer... - Franciscans International (DE)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gelobt seist du, mein Herr, durch Bruder Feuer... - Franciscans International (DE)\" \/>\n<meta property=\"og:description\" content=\"Dieser Artikel ist Teil einer Reihe von Betrachtungen, die von unserem internationalen Vorstand anl\u00e4sslich des 800-j\u00e4hrigen Jubil\u00e4ums des Sonnengesangs verfasst ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/\" \/>\n<meta property=\"og:site_name\" content=\"Franciscans International (DE)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranciscansInternational\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T10:15:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscansinternational.org\/de\/wp-content\/uploads\/sites\/4\/2025\/07\/CanticleReflections_Fire.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FranciscansIntl\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/gelobt-seist-du-mein-herr-durch-bruder-feuer\\\/\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/gelobt-seist-du-mein-herr-durch-bruder-feuer\\\/\",\"name\":\"Gelobt seist du, mein Herr, durch Bruder Feuer... - Franciscans International (DE)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/gelobt-seist-du-mein-herr-durch-bruder-feuer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/gelobt-seist-du-mein-herr-durch-bruder-feuer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/07\\\/CanticleReflections_Fire.jpg\",\"datePublished\":\"2025-07-22T10:15:33+00:00\",\"dateModified\":\"2025-07-22T10:15:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/gelobt-seist-du-mein-herr-durch-bruder-feuer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/gelobt-seist-du-mein-herr-durch-bruder-feuer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/gelobt-seist-du-mein-herr-durch-bruder-feuer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/07\\\/CanticleReflections_Fire.jpg\",\"contentUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/07\\\/CanticleReflections_Fire.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/gelobt-seist-du-mein-herr-durch-bruder-feuer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spirituelle Reflektionen\",\"item\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/reflection\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gelobt seist du, mein Herr, durch Bruder Feuer&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/\",\"name\":\"Franciscans International (DE)\",\"description\":\"Just another Franciscans International site\",\"publisher\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/#organization\",\"name\":\"Franciscans International (DE)\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/05\\\/logo-3.png\",\"contentUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/05\\\/logo-3.png\",\"width\":1200,\"height\":205,\"caption\":\"Franciscans International (DE)\"},\"image\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranciscansInternational\\\/\",\"https:\\\/\\\/x.com\\\/FranciscansIntl\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCexu0i-fWB4wwrlPMCz8_Zg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gelobt seist du, mein Herr, durch Bruder Feuer... - Franciscans International (DE)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/","og_locale":"de_DE","og_type":"article","og_title":"Gelobt seist du, mein Herr, durch Bruder Feuer... - Franciscans International (DE)","og_description":"Dieser Artikel ist Teil einer Reihe von Betrachtungen, die von unserem internationalen Vorstand anl\u00e4sslich des 800-j\u00e4hrigen Jubil\u00e4ums des Sonnengesangs verfasst ...","og_url":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/","og_site_name":"Franciscans International (DE)","article_publisher":"https:\/\/www.facebook.com\/FranciscansInternational\/","article_modified_time":"2025-07-22T10:15:35+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/franciscansinternational.org\/de\/wp-content\/uploads\/sites\/4\/2025\/07\/CanticleReflections_Fire.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@FranciscansIntl","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/","url":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/","name":"Gelobt seist du, mein Herr, durch Bruder Feuer... - Franciscans International (DE)","isPartOf":{"@id":"https:\/\/franciscansinternational.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/#primaryimage"},"image":{"@id":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/#primaryimage"},"thumbnailUrl":"https:\/\/franciscansinternational.org\/de\/wp-content\/uploads\/sites\/4\/2025\/07\/CanticleReflections_Fire.jpg","datePublished":"2025-07-22T10:15:33+00:00","dateModified":"2025-07-22T10:15:35+00:00","breadcrumb":{"@id":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/#primaryimage","url":"https:\/\/franciscansinternational.org\/de\/wp-content\/uploads\/sites\/4\/2025\/07\/CanticleReflections_Fire.jpg","contentUrl":"https:\/\/franciscansinternational.org\/de\/wp-content\/uploads\/sites\/4\/2025\/07\/CanticleReflections_Fire.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/franciscansinternational.org\/de\/reflection\/gelobt-seist-du-mein-herr-durch-bruder-feuer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscansinternational.org\/de\/"},{"@type":"ListItem","position":2,"name":"Spirituelle Reflektionen","item":"https:\/\/franciscansinternational.org\/de\/reflection\/"},{"@type":"ListItem","position":3,"name":"Gelobt seist du, mein Herr, durch Bruder Feuer&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/franciscansinternational.org\/de\/#website","url":"https:\/\/franciscansinternational.org\/de\/","name":"Franciscans International (DE)","description":"Just another Franciscans International site","publisher":{"@id":"https:\/\/franciscansinternational.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscansinternational.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/franciscansinternational.org\/de\/#organization","name":"Franciscans International (DE)","url":"https:\/\/franciscansinternational.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/franciscansinternational.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/franciscansinternational.org\/wp-content\/uploads\/sites\/4\/2023\/05\/logo-3.png","contentUrl":"https:\/\/franciscansinternational.org\/wp-content\/uploads\/sites\/4\/2023\/05\/logo-3.png","width":1200,"height":205,"caption":"Franciscans International (DE)"},"image":{"@id":"https:\/\/franciscansinternational.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranciscansInternational\/","https:\/\/x.com\/FranciscansIntl","https:\/\/www.youtube.com\/channel\/UCexu0i-fWB4wwrlPMCz8_Zg"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/franciscansinternational.org\/de\/wp-json\/wp\/v2\/reflection\/794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franciscansinternational.org\/de\/wp-json\/wp\/v2\/reflection"}],"about":[{"href":"https:\/\/franciscansinternational.org\/de\/wp-json\/wp\/v2\/types\/reflection"}],"version-history":[{"count":3,"href":"https:\/\/franciscansinternational.org\/de\/wp-json\/wp\/v2\/reflection\/794\/revisions"}],"predecessor-version":[{"id":804,"href":"https:\/\/franciscansinternational.org\/de\/wp-json\/wp\/v2\/reflection\/794\/revisions\/804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscansinternational.org\/de\/wp-json\/wp\/v2\/media\/795"}],"wp:attachment":[{"href":"https:\/\/franciscansinternational.org\/de\/wp-json\/wp\/v2\/media?parent=794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}