{"id":715,"date":"2024-10-10T08:52:18","date_gmt":"2024-10-10T08:52:18","guid":{"rendered":"https:\/\/franciscansinternational.org\/es\/?p=715"},"modified":"2024-10-10T10:20:33","modified_gmt":"2024-10-10T10:20:33","slug":"declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu","status":"publish","type":"post","link":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/","title":{"rendered":"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU"},"content":{"rendered":"\n<p>El Consejo de Derechos Humanos se reuni\u00f3 para llevar a cabo su 57\u00ba periodo de sesiones entre el 9 de septiembre y el 9 de octubre de 2024. En los p\u00e1rrafos siguientes, y a medida que se pongan disponibles,\u00a0 ser\u00e1 posible encontrar todas nuestras declaraciones emitidas durante este periodo de sesiones. Nuestras intervenciones anteriores en defensa de los derechos humanos est\u00e1n disponibles <a href=\"https:\/\/franciscansinternational.org\/es\/resources\/intervenciones-de-incidencia\/\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p><strong>\u00cdtem 10: Debate general &#8211; Filipinas (9 de octubre)<\/strong><br><br>A pesar de sus inherentes debilidades y defectos, el recientemente concluido Programa Conjunto de la ONU para los Derechos Humanos en Filipinas ha sido publicitado como un modelo para hacer operativo el Tema 10 de la Agenda del Consejo. Sin embargo, a su conclusi\u00f3n, el Programa Conjunto s\u00f3lo ha servido para consolidar a\u00fan m\u00e1s la impunidad y proteger al gobierno del escrutinio sobre cuestiones clave de derechos humanos. En una declaraci\u00f3n conjunta, hemos demandado un examen objetivo e independiente no s\u00f3lo para atender los graves problemas de derechos humanos en Filipinas, sino tambi\u00e9n para garantizar que el Consejo no repita sus errores en otros lugares.<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/10\/HRC57_Item10_Philippines.pdf\">Declaraci\u00f3n completa (en ingl\u00e9s)<\/a><br><br><strong>Panel anual sobre los derechos de los pueblos ind\u00edgenas &#8211; Guatemala (25 de septiembre)<\/strong><br><br>Hace diecisiete a\u00f1os, la Declaraci\u00f3n de la ONU sobre los Derechos de los Pueblos Ind\u00edgenas reconoci\u00f3 su derecho a la autodeterminaci\u00f3n y la obligaci\u00f3n del Estado de impedir cualquier acto que condujera al despojo de las tierras ind\u00edgenas. Sin embargo, hoy en d\u00eda existen muchos obst\u00e1culos para lograr estos objetivos. Durante el Consejo de Derechos Humanos, hemos alzado la voz mencionando el caso de una mina de n\u00edquel en El Estor, Guatemala, que opera en tierras ind\u00edgenas sin el consentimiento libre, previo e informado de la comunidad y ha causado da\u00f1os medioambientales amplios y de largo alcance. En una declaraci\u00f3n conjunta, hemos pedido a Guatemala que cumpla con sus obligaciones internacionales y garantice el cumplimiento de la Declaraci\u00f3n sobre los Derechos de los Pueblos Ind\u00edgenas.<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/09\/HRC57_IndigenousPeoples_Guatemala.pdf\">Declaraci\u00f3n completa \u00a0(en espa\u00f1ol)<\/a><br><br><strong>\u00cdtem 4: Debate General &#8211; Mozambique (25 de septiembre)<\/strong><br><br>M\u00e1s de medio mill\u00f3n de personas siguen desplazadas por el conflicto en el norte de Mozambique. M\u00e1s de 1,5 millones se enfrentan a condiciones humanitarias terribles, con acceso limitado a alimentos, albergue, agua, saneamiento y educaci\u00f3n, lo que les hace vulnerables a la radicalizaci\u00f3n por parte de organizaciones extremistas. Las narrativas oficiales sobre el conflicto en Cabo Delgado ignoran las disparidades socioecon\u00f3micas que alimentan el conflicto, impulsado en parte por las empresas transnacionales que explotan los recursos naturales. Hemos instado a Mozambique a que cumpla con sus obligaciones internacionales en materia de derechos humanos y derecho humanitario, incluso regulando las empresas que operan en esta situaci\u00f3n de conflicto.<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/09\/HRC57_Item4_Mozambique.pdf\">Declaraci\u00f3n completa (en ingl\u00e9s)<\/a><br><br><strong>\u00cdtem 4: Debate general &#8211; Indonesia (25 de septiembre)<\/strong><br><br>En una declaraci\u00f3n conjunta, expresamos nuestra preocupaci\u00f3n por el uso innecesario y severo de la fuerza contra los manifestantes que se opon\u00edan al proyecto de ley de elecciones regionales a finales de agosto y contra los periodistas que cubr\u00edan las manifestaciones. Los informes sobre detenciones en r\u00e9gimen de incomunicaci\u00f3n durante las redadas policiales y las severas palizas propinadas a los manifestantes reflejan un patr\u00f3n m\u00e1s amplio de escalada de las violaciones de los derechos humanos en Indonesia. En vista de ello, nuestra preocupaci\u00f3n se extiende a las enmiendas legales propuestas que ampliar\u00edan indebidamente el poder policial y permitir\u00edan una participaci\u00f3n militar injustificada en la gobernanza civil.<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/10\/HRC57_Item4_GD_Indonesia.pdf\">Declaraci\u00f3n completa (en ingl\u00e9s)<\/a><br><br><strong>\u00cdtem 4: Debate general &#8211; Honduras (19 de septiembre)<\/strong>\u00a0<br><br>Aunque Honduras se comprometi\u00f3 en 2023 a dejar de utilizar coque de petr\u00f3leo y carb\u00f3n, sigue facilitando un proyecto termoel\u00e9ctrico en el municipio de Tocoa, que depende del coque de petr\u00f3leo. Los estudios de impacto ambiental presentados por la empresa en cuesti\u00f3n contienen informaci\u00f3n vaga, incompleta y deficiente, y las autoridades deber\u00edan haber cancelado el proyecto desde el principio. En vez de eso, los miembros de la comunidad que se oponen al proyecto han sido objeto de ataques que culminaron con el brutal asesinato del activista medioambiental Juan Antonio L\u00f3pez el 14 de septiembre. En el Consejo de Derechos Humanos, hemos insistido en que Honduras debe cumplir urgentemente sus obligaciones en materia de derechos humanos para proteger a su poblaci\u00f3n, y hacer que las empresas y los funcionarios p\u00fablicos rindan cuentas por sus acciones y su negligencia.\u00a0<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/09\/HRC57_Item3_GeneralDebate_Honduras.pdf\">Declaraci\u00f3n completa (en espa\u00f1ol)<\/a><br><br><strong>\u00cdtem 3: Di\u00e1logo interactivo con el Relator Especial sobre sustancias t\u00f3xicas y derechos humanos &#8211; Guatemala (17 de septiembre)<\/strong><br><br>Las desenfrenadas actividades empresariales en Guatemala est\u00e1n teniendo un impacto negativo tanto en el medio ambiente como en la vida y los derechos humanos de los pueblos ind\u00edgenas. La extracci\u00f3n de minerales ha contaminado los acu\u00edferos con metales pesados. Las agroindustrias han contaminado el suelo y las cuencas hidrogr\u00e1ficas con pesticidas. Esto ha provocado el deterioro del medio ambiente, la destrucci\u00f3n de los ecosistemas, la p\u00e9rdida de biodiversidad y el aumento de los riesgos para la salud, la seguridad alimentaria, los medios de subsistencia y la cultura de los pueblos ind\u00edgenas del pa\u00eds. Guatemala debe cumplir urgentemente sus obligaciones internacionales regulando y controlando las industrias extractivas. En la 57\u00aa sesi\u00f3n del CDH hemos instado al gobierno a ratificar el Acuerdo de Escaz\u00fa como un paso esencial hacia este objetivo.\u00a0<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/09\/HRC57_Item3_GeneralDebate_Honduras.pdf\">Declaraci\u00f3n completa (en espa\u00f1ol)<\/a><br><br><strong>\u00cdtem 3: Di\u00e1logo interactivo sobre el Informe del Secretario General sobre los efectos de las p\u00e9rdidas y da\u00f1os causados por el cambio clim\u00e1tico (13 de septiembre)<br><\/strong><br>Las p\u00e9rdidas y da\u00f1os causados por el cambio clim\u00e1tico van mucho m\u00e1s all\u00e1 de la destrucci\u00f3n material, afectando profundamente a la dignidad humana, la identidad cultural y el bienestar emocional. Junto con el Foro Interreligioso de Ginebra sobre Cambio Clim\u00e1tico, Medio Ambiente y Derechos Humanos (GIF) hemos destacado la posici\u00f3n \u00fanica de las comunidades religiosas a la hora de responder a los retos que plantean las p\u00e9rdidas y los da\u00f1os no econ\u00f3micos. Hicimos un llamamiento al Consejo para que integre estos puntos de vista en las pol\u00edticas como forma de reforzar los marcos internacionales de derechos humanos y garantizar que las p\u00e9rdidas y da\u00f1os no econ\u00f3micos se aborden de una forma m\u00e1s hol\u00edstica, culturalmente sensible y centrada en el ser humano.<\/p>\n\n\n\n<p>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/09\/HRC57_Item3_LossDamage.pdf\">Declaraci\u00f3n completa (en ingl\u00e9s)<\/a><br><br><strong>\u00cdtem 2: Debate general &#8211; Guatemala (11 de septiembre)<br><\/strong><br>Como ha se\u00f1alado la Alta Comisionada de la ONU para los Derechos Humanos, en Guatemala se ha hecho un uso indebido del derecho penal para perseguir a defensores de los derechos humanos, operadores de justicia, periodistas, estudiantes y autoridades ind\u00edgenas. En este contexto, el pr\u00f3ximo proceso de selecci\u00f3n de nuevos magistrados para la Corte Suprema de Justicia y la Corte de Apelaciones es crucial. En una declaraci\u00f3n conjunta, pedimos a la comunidad internacional que observe los procedimientos, apoye a las organizaciones de la sociedad civil que ya lo est\u00e1n haciendo y destaque la importancia de un proceso transparente.<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/10\/HRC57_Item2_GD_Guatemala.pdf\">Declaraci\u00f3n completa (en espa\u00f1ol)<\/a><br><strong>\u00a0\u00cdtem 2: Debate general &#8211; Camer\u00fan (10 de septiembre)<\/strong><br><br>Aunque recibimos con satisfacci\u00f3n la reciente visita del Alto Comisionado de las Naciones Unidas para los Derechos Humanos, seguimos preocupados por la persistente impunidad de las graves violaciones de los derechos humanos cometidas en Camer\u00fan desde 2017. Los violentos enfrentamientos entre el ej\u00e9rcito nacional y los grupos armados no estatales siguen teniendo un profundo impacto en la poblaci\u00f3n civil. Con las elecciones presidenciales previstas para el pr\u00f3ximo a\u00f1o, hemos emitido esta declaraci\u00f3n conjunta para pedir a las autoridades que creen las condiciones necesarias para una votaci\u00f3n pac\u00edfica y transparente, en l\u00ednea con las normas internacionales. Tambi\u00e9n instamos al gobierno a crear condiciones favorables para la paz y la reconciliaci\u00f3n nacional.<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/10\/HRC57_Item2GD_Cameroon.pdf\">Declaraci\u00f3n completa (en franc\u00e9s)\u00a0<\/a><br><br><strong>\u00cdtem 2: Di\u00e1logo interactivo sobre el Informe de la OACDH sobre Sri Lanka (9 de septiembre)<\/strong><br><br>Sri Lanka no ha logrado avances significativos en el cumplimiento de sus obligaciones en materia de derechos humanos. Franciscans International expres\u00f3 su preocupaci\u00f3n por la falta de mecanismos de rendici\u00f3n de cuentas para las v\u00edctimas de desapariciones forzadas y otras violaciones en el pasado y en el presente, as\u00ed como por la falta de avances en las investigaciones sobre los atentados del Domingo de Resurrecci\u00f3n de 2019. En este sentido, instamos al Consejo a renovar el mandato de la OACDH y su proyecto de rendici\u00f3n de cuentas en Sri Lanka durante al menos dos a\u00f1os.<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/09\/HRC57_Item2_SriLanka.pdf\">Declaraci\u00f3n completa (en ingl\u00e9s)<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color\" style=\"color:#195995\"><strong><em>Declaraciones escritas<\/em><\/strong><\/p>\n\n\n\n<p><strong>Situaci\u00f3n de los Derechos Humanos en Camer\u00fan: Procesos significativos de resoluci\u00f3n de conflictos y rendici\u00f3n de cuentas<\/strong><br><br>Los violentos enfrentamientos entre &lt;separatistas armados y el ej\u00e9rcito siguen teniendo un profundo impacto en la poblaci\u00f3n civil de Camer\u00fan, con violaciones de los derechos humanos cometidas por ambos bandos. La rendici\u00f3n de cuentas sigue siendo una realidad lejana ya que las denuncias de las v\u00edctimas rara vez desembocan en procesos judiciales, lo que erosiona la confianza en los procesos judiciales. Antes del Consejo de Derechos Humanos, formulamos varias recomendaciones para abordar las causas profundas del conflicto y entablar procesos significativos de rendici\u00f3n de cuentas, entre otras cosas, aplicando la igualdad ling\u00fc\u00edstica, estableciendo un marco jur\u00eddico adecuado, garantizando el acceso seguro a la ayuda humanitaria y m\u00e9dica, y entablando un di\u00e1logo constructivo con todas las partes.<br><br>\u2022 <a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/10\/HRC57-WrittenStatement-Cameroon.pdf\">Declaraci\u00f3n completa (en ingl\u00e9s)<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-small-font-size\">Thumbnail photo: UN Photo \/ Jean Marc Ferr\u00e9<\/p>\n\n\n\n<p class=\"has-text-align-left has-text-color\" style=\"color:#195995\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de Derechos Humanos se reuni\u00f3 para llevar a cabo su 57\u00ba periodo de sesiones entre el 9 de &#8230; <\/p>\n","protected":false},"author":3,"featured_media":717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"313,201,408,325,397,419","_relevanssi_noindex_reason":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[5,7,10,6],"class_list":["post-715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-programa-africa","tag-programa-asia-pacifico","tag-programa-europa","tag-programa-para-las-americas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU - Franciscans International (ES)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU - Franciscans International (ES)\" \/>\n<meta property=\"og:description\" content=\"El Consejo de Derechos Humanos se reuni\u00f3 para llevar a cabo su 57\u00ba periodo de sesiones entre el 9 de ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/\" \/>\n<meta property=\"og:site_name\" content=\"Franciscans International (ES)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranciscansInternational\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-10T08:52:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-10T10:20:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscansinternational.org\/es\/wp-content\/uploads\/sites\/3\/2024\/10\/HRC57_thumbnail_JMFerre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"539\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"communications\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FranciscansIntl\" \/>\n<meta name=\"twitter:site\" content=\"@FranciscansIntl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"communications\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/\"},\"author\":{\"name\":\"communications\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#\\\/schema\\\/person\\\/f398f02712a9dcab7603295bc1ea94e4\"},\"headline\":\"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU\",\"datePublished\":\"2024-10-10T08:52:18+00:00\",\"dateModified\":\"2024-10-10T10:20:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/\"},\"wordCount\":1643,\"publisher\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/HRC57_thumbnail_JMFerre.jpg\",\"keywords\":[\"Programa \u00c1frica\",\"Programa Asia-Pac\u00edfico\",\"Programa Europa\",\"Programa para las Am\u00e9ricas\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/\",\"name\":\"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU - Franciscans International (ES)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/HRC57_thumbnail_JMFerre.jpg\",\"datePublished\":\"2024-10-10T08:52:18+00:00\",\"dateModified\":\"2024-10-10T10:20:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/HRC57_thumbnail_JMFerre.jpg\",\"contentUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/HRC57_thumbnail_JMFerre.jpg\",\"width\":1024,\"height\":539},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/\",\"name\":\"Franciscans International (ES)\",\"description\":\"Just another Franciscans International site\",\"publisher\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#organization\",\"name\":\"Franciscans International (ES)\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/logo-3.png\",\"contentUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/logo-3.png\",\"width\":1200,\"height\":205,\"caption\":\"Franciscans International (ES)\"},\"image\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranciscansInternational\\\/\",\"https:\\\/\\\/x.com\\\/FranciscansIntl\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCexu0i-fWB4wwrlPMCz8_Zg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/#\\\/schema\\\/person\\\/f398f02712a9dcab7603295bc1ea94e4\",\"name\":\"communications\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b4a62226a9b4f7ce621ec49ca40be1e77d886a42ca84b8a0b0697e9ec17dd63?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b4a62226a9b4f7ce621ec49ca40be1e77d886a42ca84b8a0b0697e9ec17dd63?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b4a62226a9b4f7ce621ec49ca40be1e77d886a42ca84b8a0b0697e9ec17dd63?s=96&d=mm&r=g\",\"caption\":\"communications\"},\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/es\\\/author\\\/communications\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU - Franciscans International (ES)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/","og_locale":"es_ES","og_type":"article","og_title":"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU - Franciscans International (ES)","og_description":"El Consejo de Derechos Humanos se reuni\u00f3 para llevar a cabo su 57\u00ba periodo de sesiones entre el 9 de ...","og_url":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/","og_site_name":"Franciscans International (ES)","article_publisher":"https:\/\/www.facebook.com\/FranciscansInternational\/","article_published_time":"2024-10-10T08:52:18+00:00","article_modified_time":"2024-10-10T10:20:33+00:00","og_image":[{"width":1024,"height":539,"url":"https:\/\/franciscansinternational.org\/es\/wp-content\/uploads\/sites\/3\/2024\/10\/HRC57_thumbnail_JMFerre.jpg","type":"image\/jpeg"}],"author":"communications","twitter_card":"summary_large_image","twitter_creator":"@FranciscansIntl","twitter_site":"@FranciscansIntl","twitter_misc":{"Escrito por":"communications","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/#article","isPartOf":{"@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/"},"author":{"name":"communications","@id":"https:\/\/franciscansinternational.org\/es\/#\/schema\/person\/f398f02712a9dcab7603295bc1ea94e4"},"headline":"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU","datePublished":"2024-10-10T08:52:18+00:00","dateModified":"2024-10-10T10:20:33+00:00","mainEntityOfPage":{"@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/"},"wordCount":1643,"publisher":{"@id":"https:\/\/franciscansinternational.org\/es\/#organization"},"image":{"@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/#primaryimage"},"thumbnailUrl":"https:\/\/franciscansinternational.org\/es\/wp-content\/uploads\/sites\/3\/2024\/10\/HRC57_thumbnail_JMFerre.jpg","keywords":["Programa \u00c1frica","Programa Asia-Pac\u00edfico","Programa Europa","Programa para las Am\u00e9ricas"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/","url":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/","name":"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU - Franciscans International (ES)","isPartOf":{"@id":"https:\/\/franciscansinternational.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/#primaryimage"},"image":{"@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/#primaryimage"},"thumbnailUrl":"https:\/\/franciscansinternational.org\/es\/wp-content\/uploads\/sites\/3\/2024\/10\/HRC57_thumbnail_JMFerre.jpg","datePublished":"2024-10-10T08:52:18+00:00","dateModified":"2024-10-10T10:20:33+00:00","breadcrumb":{"@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/#primaryimage","url":"https:\/\/franciscansinternational.org\/es\/wp-content\/uploads\/sites\/3\/2024\/10\/HRC57_thumbnail_JMFerre.jpg","contentUrl":"https:\/\/franciscansinternational.org\/es\/wp-content\/uploads\/sites\/3\/2024\/10\/HRC57_thumbnail_JMFerre.jpg","width":1024,"height":539},{"@type":"BreadcrumbList","@id":"https:\/\/franciscansinternational.org\/es\/declaraciones-en-la-57a-sesion-del-consejo-de-derechos-humanos-de-la-onu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscansinternational.org\/es\/"},{"@type":"ListItem","position":2,"name":"Declaraciones en la 57\u00aa Sesi\u00f3n del Consejo de Derechos Humanos de la ONU"}]},{"@type":"WebSite","@id":"https:\/\/franciscansinternational.org\/es\/#website","url":"https:\/\/franciscansinternational.org\/es\/","name":"Franciscans International (ES)","description":"Just another Franciscans International site","publisher":{"@id":"https:\/\/franciscansinternational.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscansinternational.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/franciscansinternational.org\/es\/#organization","name":"Franciscans International (ES)","url":"https:\/\/franciscansinternational.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/franciscansinternational.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/franciscansinternational.org\/wp-content\/uploads\/sites\/3\/2023\/05\/logo-3.png","contentUrl":"https:\/\/franciscansinternational.org\/wp-content\/uploads\/sites\/3\/2023\/05\/logo-3.png","width":1200,"height":205,"caption":"Franciscans International (ES)"},"image":{"@id":"https:\/\/franciscansinternational.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranciscansInternational\/","https:\/\/x.com\/FranciscansIntl","https:\/\/www.youtube.com\/channel\/UCexu0i-fWB4wwrlPMCz8_Zg"]},{"@type":"Person","@id":"https:\/\/franciscansinternational.org\/es\/#\/schema\/person\/f398f02712a9dcab7603295bc1ea94e4","name":"communications","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0b4a62226a9b4f7ce621ec49ca40be1e77d886a42ca84b8a0b0697e9ec17dd63?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b4a62226a9b4f7ce621ec49ca40be1e77d886a42ca84b8a0b0697e9ec17dd63?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b4a62226a9b4f7ce621ec49ca40be1e77d886a42ca84b8a0b0697e9ec17dd63?s=96&d=mm&r=g","caption":"communications"},"url":"https:\/\/franciscansinternational.org\/es\/author\/communications\/"}]}},"jetpack_featured_media_url":"https:\/\/franciscansinternational.org\/es\/wp-content\/uploads\/sites\/3\/2024\/10\/HRC57_thumbnail_JMFerre.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/posts\/715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/comments?post=715"}],"version-history":[{"count":4,"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/posts\/715\/revisions"}],"predecessor-version":[{"id":720,"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/posts\/715\/revisions\/720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/media\/717"}],"wp:attachment":[{"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/media?parent=715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/categories?post=715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/franciscansinternational.org\/es\/wp-json\/wp\/v2\/tags?post=715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}