{"id":889,"date":"2025-12-08T11:24:18","date_gmt":"2025-12-08T11:24:18","guid":{"rendered":"https:\/\/franciscansinternational.org\/it\/?post_type=reflection&#038;p=889"},"modified":"2025-12-08T11:33:19","modified_gmt":"2025-12-08T11:33:19","slug":"sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra","status":"publish","type":"reflection","link":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/","title":{"rendered":"Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra&#8230;"},"content":{"rendered":"\n<p><em>Questo articolo fa parte di <a href=\"https:\/\/franciscansinternational.org\/it\/celebrazione-del-cantico-delle-creature\/\" target=\"_blank\" rel=\"noreferrer noopener\">una serie di riflessioni<\/a> scritte dal nostro <a href=\"https:\/\/franciscansinternational.org\/it\/chi-siamo\/#ilconsigliodiamministrazioneinternazionale\" target=\"_blank\" rel=\"noreferrer noopener\">Consiglio di Amministrazione Internazionale<\/a> per celebrare gli 800 anni del Cantico delle<em> Creature.<\/em><\/em><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-color has-text-color has-link-color wp-elements-1c436cee45f1c494dfd5a54875f61579\">\u2022 \u2022 \u2022<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra, che ci sostiene e ci governa,<\/em> <em>producendo frutti vari con fiori colorati ed erbe.<\/em><\/p>\n\n\n\n<p><em>&#8211; San Francesco d&#8217;Assisi, Cantico delle creature<\/em><\/p>\n\n\n\n<p>Queste parole tratte dal Cantico delle creature \u2013 o&nbsp;<em>Cantico di Fratello Sole<\/em>&nbsp;\u2013 composto da San Francesco d&#8217;Assisi nel 1225-26 rivelano la sua comprensione di un universo creato nell&#8217;amore e per l&#8217;amore, profondamente interpersonale, interconnesso, integro. Come ci ricorda Papa Francesco, riflettendo sull&#8217;origine e sul significato della creazione e ispirandosi al&nbsp;<em>Cantico<\/em>&nbsp;di San Francesco: \u00abL&#8217;universo non \u00e8 il frutto di un&#8217;onnipotenza arbitraria, di una dimostrazione di forza o di un desiderio di autoaffermazione. La creazione \u00e8 l&#8217;ordine dell&#8217;amore. L&#8217;amore di Dio \u00e8 la forza motrice fondamentale di tutte le cose create\u00bb (<em>Laudato SI:<\/em>&nbsp;77).<\/p>\n\n\n\n<p>Quando riflettiamo su Madre Terra, riconosciamo il pianeta come un sistema unico, complesso e interconnesso. Questa prospettiva integrale riconosce le intricate relazioni tra i componenti fisici della Terra (geosfera, idrosfera, atmosfera), i suoi organismi viventi (biosfera) e l&#8217;impatto potente e spesso dannoso dell&#8217;umanit\u00e0. La Terra fornisce risorse fondamentali essenziali per tutta la vita: un flusso continuo di energia; acqua liquida; un&#8217;atmosfera stabile e adatta con gas vitali; composti organici e sostanze nutritive; temperature moderate; e ingredienti chimici vitali. Madre Sorella Terra ci fornisce anche un campo magnetico che protegge la vita dalle radiazioni solari dannose, e la tettonica a zolle e le stagioni che contribuiscono all&#8217;abitabilit\u00e0 del pianeta. Vista in questo modo, la Terra \u00e8 un organismo vivente che fornisce le condizioni necessarie alla sopravvivenza di tutti gli abitanti della vita.&nbsp;<\/p>\n\n\n\n<p>San Francesco apre una nuova strada all&#8217;interno del cristianesimo occidentale quando parla della Sorella Madre Terra che svolge un doppio ruolo di sostegno e&nbsp;<em>governo di&nbsp;<\/em>tutti i membri della comunit\u00e0 terrestre. In primo luogo, San Francesco riconosce la personalit\u00e0 e l&#8217;azione di tutte le creature: \u201cFratello Sole, Sorella Luna, Madre Sorella Terra\u201d. Ma San Francesco fa un passo in pi\u00f9. Secondo Christiana Garzena, \u00abla rivoluzione francescana consiste nell&#8217;affermazione che la terra sostiene e governa&#8230; L&#8217;esegesi biblica precedente a Francesco sosteneva che gli esseri umani dovessero dominare la terra&#8230; Egli \u00e8 il primo a contestare questo principio\u00bb (cfr. Jacques Delarun, Il Cantico di Frate Sole, Assisi, Biblioteca Francescana, 2015:55). Non \u00e8 missione degli esseri umani controllare, dominare, deturpare, distruggere e scartare tutto ci\u00f2 che troviamo utile nel mondo naturale. Siamo chiamati da Dio e da San Francesco a riconoscere il nostro posto come co-creature e compagni di viaggio di Sorella Madre Terra che, in definitiva, ci fornisce tutto ci\u00f2 di cui abbiamo bisogno per sopravvivere.<\/p>\n\n\n\n<p>Se ci sono dubbi su chi governa chi, basta guardare agli eventi meteorologici sempre pi\u00f9 violenti e distruttivi &#8211; ondate di calore, siccit\u00e0, inondazioni, incendi, uragani, ecc. &#8211; il modo in cui la natura ci ricorda che, in realt\u00e0, non siamo i padroni e gli dei del nostro destino. Siamo partner dipendenti, interdipendenti e corresponsabili con tutto il creato, chiamati a rispondere alla nostra specifica vocazione di amare, rispettare e prenderci cura di tutti i membri della comunit\u00e0 terrestre, non umani e umani. Quando accettiamo la natura della nostra identit\u00e0 di creature dipendenti e interdipendenti; quando riconosciamo che nostra sorella Madre Terra e tutto il creato sono dotati di personalit\u00e0 e capacit\u00e0 di agire; quando apriamo le nostre vite a un processo permanente di \u201cconversione ecologica\u201d; ci troveremo sulla strada verso l&#8217;autentica saggezza, una saggezza profondamente spirituale ma anche una saggezza che richiede sforzi urgenti, concreti e congiunti per affrontare le cause del cambiamento climatico e le minacce alla biodiversit\u00e0 e all&#8217;esistenza futura di innumerevoli milioni di esseri umani e di innumerevoli altre forme di vita (cfr. Papa Francesco,&nbsp;<em>Laudate Deum<\/em>;&nbsp;<a href=\"https:\/\/franciscansinternational.org\/wp-content\/uploads\/2024\/10\/R2HE_FI_2024_ENG.pdf\">Franciscans International,&nbsp;<em>The Right to a Healthy Environment<\/em><\/a>).<\/p>\n\n\n\n<p>Ma in che modo la via della saggezza pu\u00f2 condurci a un nuovo rapporto con il creato? Papa Francesco, in&nbsp;<em>Querida Amazonia&nbsp;<\/em>(42), riflette sulle numerose culture indigene globali che continuano a seguire un approccio basato sulla saggezza nel loro rapporto con il creato. Egli scrive: \u00abLa saggezza dei popoli originari dell&#8217;Amazzonia ispira cura e rispetto per il creato, con una chiara consapevolezza dei suoi limiti, e ne proibisce l&#8217;abuso. Abusare della natura significa abusare dei nostri antenati, dei nostri fratelli e sorelle, del creato e del Creatore, e ipotecare il futuro\u00bb. Per San Francesco e Papa Francesco, questo modo relazionale di saggezza in cui tutti i membri del creato sono riconosciuti come fratelli e sorelle \u00e8 l&#8217;unica via in grado di ripristinare il giusto rapporto e la piena comunione con Dio, con gli altri e con tutto il creato. Se seguiamo questa via, permettendo che una conversione ecologica attecchisca in noi, saremo in grado di riconoscere il \u00abgrido della terra [e il] grido dei [fratelli e delle sorelle] poveri\u00bb (<em>Laudato Si\u2019:<\/em>49) e la nostra responsabilit\u00e0 di rispondere.<\/p>\n\n\n\n<p>Uniamoci nella preghiera e nell&#8217;azione. Possano i nostri sforzi che precedono e seguono la 30^a riunione della conferenza delle Nazioni Unite sui cambiamenti climatici (COP-30) a Belem, in Brasile, nel novembre 2025, servire a promuovere una conversione ecologica profonda e duratura e l&#8217;avvio di un processo di guarigione e di restaurazione. Abbracciamo la nostra vocazione e missione di lodare Dio attraverso l&#8217;amore e la cura per tutto il creato. Possa la nostra sorella Madre Terra insegnarci la via della saggezza, dell&#8217;unit\u00e0 e dell&#8217;armonia.&nbsp;<em>Laudato Si\u2019, o mi Signore! Sia lodato Tu, mio Signore!<\/em><\/p>\n\n\n\n<p><em>&#8211; Di fratello Michael A. Perry OFM<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-background has-small-font-size\" style=\"background-color:#f4f5f6\">Si tratta di una traduzione automatica. Ci scusiamo per gli eventuali errori che ne derivano. In caso di divergenze, fa fede la versione inglese.\u00a0\u00a0<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo articolo fa parte di una serie di riflessioni scritte dal nostro Consiglio di Amministrazione Internazionale per celebrare gli 800 &#8230; <\/p>\n","protected":false},"featured_media":890,"template":"","class_list":["post-889","reflection","type-reflection","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra... - Franciscans International (IT)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra... - Franciscans International (IT)\" \/>\n<meta property=\"og:description\" content=\"Questo articolo fa parte di una serie di riflessioni scritte dal nostro Consiglio di Amministrazione Internazionale per celebrare gli 800 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/\" \/>\n<meta property=\"og:site_name\" content=\"Franciscans International (IT)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FranciscansInternational\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-08T11:33:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/franciscansinternational.org\/it\/wp-content\/uploads\/sites\/2\/2025\/10\/IBD_Canticle_MotherEarth.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"929\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FranciscansIntl\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\\\/\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\\\/\",\"name\":\"Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra... - Franciscans International (IT)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/IBD_Canticle_MotherEarth.jpg\",\"datePublished\":\"2025-12-08T11:24:18+00:00\",\"dateModified\":\"2025-12-08T11:33:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/IBD_Canticle_MotherEarth.jpg\",\"contentUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/10\\\/IBD_Canticle_MotherEarth.jpg\",\"width\":929,\"height\":523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riflessioni spirituali\",\"item\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/reflection\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/\",\"name\":\"Franciscans International (IT)\",\"description\":\"Just another Franciscans International site\",\"publisher\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/#organization\",\"name\":\"Franciscans International\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/franciscansinternational.org\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/05\\\/logo-3.png\",\"contentUrl\":\"https:\\\/\\\/franciscansinternational.org\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/05\\\/logo-3.png\",\"width\":1200,\"height\":205,\"caption\":\"Franciscans International\"},\"image\":{\"@id\":\"https:\\\/\\\/franciscansinternational.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FranciscansInternational\\\/\",\"https:\\\/\\\/x.com\\\/FranciscansIntl\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCexu0i-fWB4wwrlPMCz8_Zg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra... - Franciscans International (IT)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/","og_locale":"it_IT","og_type":"article","og_title":"Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra... - Franciscans International (IT)","og_description":"Questo articolo fa parte di una serie di riflessioni scritte dal nostro Consiglio di Amministrazione Internazionale per celebrare gli 800 ...","og_url":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/","og_site_name":"Franciscans International (IT)","article_publisher":"https:\/\/www.facebook.com\/FranciscansInternational\/","article_modified_time":"2025-12-08T11:33:19+00:00","og_image":[{"width":929,"height":523,"url":"https:\/\/franciscansinternational.org\/it\/wp-content\/uploads\/sites\/2\/2025\/10\/IBD_Canticle_MotherEarth.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@FranciscansIntl","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/","url":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/","name":"Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra... - Franciscans International (IT)","isPartOf":{"@id":"https:\/\/franciscansinternational.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/#primaryimage"},"image":{"@id":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/#primaryimage"},"thumbnailUrl":"https:\/\/franciscansinternational.org\/it\/wp-content\/uploads\/sites\/2\/2025\/10\/IBD_Canticle_MotherEarth.jpg","datePublished":"2025-12-08T11:24:18+00:00","dateModified":"2025-12-08T11:33:19+00:00","breadcrumb":{"@id":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/#primaryimage","url":"https:\/\/franciscansinternational.org\/it\/wp-content\/uploads\/sites\/2\/2025\/10\/IBD_Canticle_MotherEarth.jpg","contentUrl":"https:\/\/franciscansinternational.org\/it\/wp-content\/uploads\/sites\/2\/2025\/10\/IBD_Canticle_MotherEarth.jpg","width":929,"height":523},{"@type":"BreadcrumbList","@id":"https:\/\/franciscansinternational.org\/it\/reflection\/sia-lodato-tu-mio-signore-attraverso-nostra-sorella-madre-terra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/franciscansinternational.org\/it\/"},{"@type":"ListItem","position":2,"name":"Riflessioni spirituali","item":"https:\/\/franciscansinternational.org\/it\/reflection\/"},{"@type":"ListItem","position":3,"name":"Sia lodato Tu, mio Signore, attraverso nostra sorella Madre Terra&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/franciscansinternational.org\/it\/#website","url":"https:\/\/franciscansinternational.org\/it\/","name":"Franciscans International (IT)","description":"Just another Franciscans International site","publisher":{"@id":"https:\/\/franciscansinternational.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/franciscansinternational.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/franciscansinternational.org\/it\/#organization","name":"Franciscans International","url":"https:\/\/franciscansinternational.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/franciscansinternational.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/franciscansinternational.org\/wp-content\/uploads\/sites\/2\/2023\/05\/logo-3.png","contentUrl":"https:\/\/franciscansinternational.org\/wp-content\/uploads\/sites\/2\/2023\/05\/logo-3.png","width":1200,"height":205,"caption":"Franciscans International"},"image":{"@id":"https:\/\/franciscansinternational.org\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FranciscansInternational\/","https:\/\/x.com\/FranciscansIntl","https:\/\/www.youtube.com\/channel\/UCexu0i-fWB4wwrlPMCz8_Zg"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/franciscansinternational.org\/it\/wp-json\/wp\/v2\/reflection\/889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/franciscansinternational.org\/it\/wp-json\/wp\/v2\/reflection"}],"about":[{"href":"https:\/\/franciscansinternational.org\/it\/wp-json\/wp\/v2\/types\/reflection"}],"version-history":[{"count":5,"href":"https:\/\/franciscansinternational.org\/it\/wp-json\/wp\/v2\/reflection\/889\/revisions"}],"predecessor-version":[{"id":939,"href":"https:\/\/franciscansinternational.org\/it\/wp-json\/wp\/v2\/reflection\/889\/revisions\/939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/franciscansinternational.org\/it\/wp-json\/wp\/v2\/media\/890"}],"wp:attachment":[{"href":"https:\/\/franciscansinternational.org\/it\/wp-json\/wp\/v2\/media?parent=889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}